{"id":787,"date":"2014-12-04T17:00:26","date_gmt":"2014-12-04T16:00:26","guid":{"rendered":"https:\/\/2015.paris.wordcamp.org\/?p=787"},"modified":"2014-12-04T17:00:26","modified_gmt":"2014-12-04T16:00:26","slug":"nouveau-sponsor-bronze-openska","status":"publish","type":"post","link":"https:\/\/paris.wordcamp.org\/2015\/nouveau-sponsor-bronze-openska\/","title":{"rendered":"Nouveau sponsor Bronze : Openska"},"content":{"rendered":"<p><a href=\"http:\/\/www.openska.com\/\" target=\"_blank\" rel=\"nofollow\">Openska<\/a>\u00a0revient cette ann\u00e9e encore parmi les sponsors sur WordCamp Paris !\u00a0Derri\u00e8re Openska se trouve notamment Cyril Pierre de Geyer, que beaucoup d\u2019entre vous connaissent comme \u00e9tant le co-auteur du best-seller \u00ab\u00a0<a href=\"http:\/\/www.editions-eyrolles.com\/Livre\/9782212134353\/php-5-avance\">PHP 5 Avanc\u00e9<\/a>\u00a0\u00bb avec \u00c9ric Daspet, comme membre fondateur et ancien pr\u00e9sident de l\u2019<a href=\"http:\/\/afup.org\/\">Association Fran\u00e7aise des Utilisateurs de PHP<\/a>, et aujourd\u2019hui comme directeur de l\u2019<a href=\"http:\/\/emba.epitech.eu\/\">Executive MBA\u00a0Epitech<\/a>. \u00a0Merci Openska !<\/p>\n<blockquote><p>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-763\" src=\"https:\/\/2015.paris.wordcamp.org\/files\/2014\/12\/logo-openska-300x117.png\" alt=\"logo-openska\" width=\"300\" height=\"117\" srcset=\"https:\/\/paris.wordcamp.org\/2015\/files\/2014\/12\/logo-openska-300x117.png 300w, https:\/\/paris.wordcamp.org\/2015\/files\/2014\/12\/logo-openska-500x195.png 500w, https:\/\/paris.wordcamp.org\/2015\/files\/2014\/12\/logo-openska.png 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>OpenSKA est un <strong><a href=\"http:\/\/www.openska.com\" rel=\"nofollow\">organisme de formation informatique<\/a><\/strong>\u00a0sp\u00e9cialis\u00e9 sur Internet et bas\u00e9 \u00e0 Paris, Lyon et Lille.<br \/>\nNos formations vont du d\u00e9veloppement de sites Web avec le langage PHP et la base MySQL \u00e0 l&rsquo;int\u00e9gration de CMS tels que <strong><a href=\"http:\/\/www.openska.com\/formation-wordpress-integrateur.php\" rel=\"nofollow\">WordPress<\/a><\/strong>\u00a0ou Drupal en passant par Java, C# ou GO. Nos valeurs sont li\u00e9es \u00e0 notre engagement et \u00e0 notre implication dans la transmission de savoir. Que vous soyez d\u00e9butant ou expert nous vous proposons des cours d&rsquo;initiation ou avanc\u00e9s au code.<br \/>\nQuelques exemples de formations de courte dur\u00e9e : La POO (Programmation Orient\u00e9e Objet) avec PHP5, le Zend Framework, la formation WordPress pour int\u00e9grateur.<\/p>\n<div>\n<p>Retrouvez l&rsquo;ensemble de nos formations\u00a0sur <a href=\"http:\/\/www.openska.com\/\" rel=\"nofollow\">Openska.com<\/a>.<\/p>\n<\/div>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Openska\u00a0revient cette ann\u00e9e encore parmi les sponsors sur WordCamp Paris !\u00a0Derri\u00e8re Openska se trouve notamment Cyril Pierre de Geyer, que beaucoup d\u2019entre vous connaissent comme \u00e9tant le co-auteur du best-seller \u00ab\u00a0PHP 5 Avanc\u00e9\u00a0\u00bb avec \u00c9ric Daspet, comme membre fondateur et ancien pr\u00e9sident de l\u2019Association Fran\u00e7aise des Utilisateurs de PHP, et aujourd\u2019hui comme directeur de l\u2019Executive [&hellip;]<\/p>\n","protected":false},"author":1185,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[336568],"tags":[],"class_list":["post-787","post","type-post","status-publish","format-standard","hentry","category-actualites"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MqRj-cH","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/posts\/787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/users\/1185"}],"replies":[{"embeddable":true,"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/comments?post=787"}],"version-history":[{"count":1,"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/posts\/787\/revisions"}],"predecessor-version":[{"id":789,"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/posts\/787\/revisions\/789"}],"wp:attachment":[{"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/media?parent=787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/categories?post=787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paris.wordcamp.org\/2015\/wp-json\/wp\/v2\/tags?post=787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}