{"id":279314,"date":"2013-12-04T17:10:25","date_gmt":"2013-12-04T16:10:25","guid":{"rendered":"https:\/\/2014.paris.wordcamp.org\/?p=279314"},"modified":"2013-12-04T21:44:17","modified_gmt":"2013-12-04T20:44:17","slug":"supinternet-accueillera-le-wordcamp-paris-dans-ses-locaux","status":"publish","type":"post","link":"https:\/\/paris.wordcamp.org\/2014\/supinternet-accueillera-le-wordcamp-paris-dans-ses-locaux\/","title":{"rendered":"SUP&rsquo;Internet accueillera le WordCamp Paris dans ses locaux"},"content":{"rendered":"<p>Comme l&rsquo;ann\u00e9e derni\u00e8re, la premi\u00e8re journ\u00e9e du WordCamp se d\u00e9roulera \u00e0 la Maison des Associations de Solidarit\u00e9 (la MAS Paris).<\/p>\n<p>Alors que nous \u00e9tions en qu\u00eate d&rsquo;un lieu pour proposer une seconde journ\u00e9e, l&rsquo;\u00e9quipe de <a href=\"http:\/\/www.supinternet.fr\/\">SUP&rsquo;Internet<\/a> a spontan\u00e9ment propos\u00e9 ses salles pour que nous puissions y faire ce second volet de l&rsquo;\u00e9v\u00e8nement.<br \/>\n<!--more--><br \/>\nGr\u00e2ce \u00e0 eux, nous allons pouvoir proposer une journ\u00e9e bien remplie et surtout bien diff\u00e9rente de la journ\u00e9e \u00ab\u00a0barcamp\u00a0\u00bb de l&rsquo;ann\u00e9e derni\u00e8re&#8230; Vous en saurez plus dans quelques jours, avec l&rsquo;annonce du programme de samedi !<\/p>\n<p>Merci SUP&rsquo;Internet !<\/p>\n<blockquote><p><a href=\"http:\/\/www.supinternet.fr\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"CMJN de base\" src=\"https:\/\/2014.paris.wordcamp.org\/files\/2013\/11\/logo-supint-hd-couleur-300x140.jpg\" width=\"300\" height=\"140\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.supinternet.fr\/\">SUP&rsquo;Internet<\/a>\u00a0propose en 3 ans une formation post-bac aux m\u00e9tiers de l&rsquo;Internet (D\u00e9veloppement, Webdesign et E-marketing). L\u2019\u00e9cole r\u00e9pond \u00e0 la demande croissante des entreprises qui ne trouvent pas aujourd&rsquo;hui ces comp\u00e9tences sur le march\u00e9 des jeunes dipl\u00f4m\u00e9s.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Comme l&rsquo;ann\u00e9e derni\u00e8re, la premi\u00e8re journ\u00e9e du WordCamp se d\u00e9roulera \u00e0 la Maison des Associations de Solidarit\u00e9 (la MAS Paris). Alors que nous \u00e9tions en qu\u00eate d&rsquo;un lieu pour proposer une seconde journ\u00e9e, l&rsquo;\u00e9quipe de SUP&rsquo;Internet a spontan\u00e9ment propos\u00e9 ses salles pour que nous puissions y faire ce second volet de l&rsquo;\u00e9v\u00e8nement.<\/p>\n","protected":false},"author":1185,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[130041],"tags":[],"class_list":["post-279314","post","type-post","status-publish","format-standard","hentry","category-annonces"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMXS-1aF4","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/279314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/users\/1185"}],"replies":[{"embeddable":true,"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/comments?post=279314"}],"version-history":[{"count":3,"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/279314\/revisions"}],"predecessor-version":[{"id":280223,"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/279314\/revisions\/280223"}],"wp:attachment":[{"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/media?parent=279314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/categories?post=279314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paris.wordcamp.org\/2014\/wp-json\/wp\/v2\/tags?post=279314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}